{"id":3858,"date":"2026-09-01T15:20:37","date_gmt":"2026-09-01T13:20:37","guid":{"rendered":"https:\/\/www.niederthalerhof.com\/glutenfrei\/"},"modified":"2026-09-01T15:39:01","modified_gmt":"2026-09-01T13:39:01","slug":"glutenfrei","status":"publish","type":"page","link":"https:\/\/www.niederthalerhof.com\/it\/glutenfrei\/","title":{"rendered":"senza glutine"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"3858\" class=\"elementor elementor-3858 elementor-3846\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5988e7ce e-con-full e-flex e-con e-parent\" data-id=\"5988e7ce\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-50a786d0 elementor-pagination-position-inside pfeillinksunten elementor-skin-carousel elementor-pagination-type-bullets elementor-widget elementor-widget-media-carousel\" data-id=\"50a786d0\" data-element_type=\"widget\" data-settings=\"{&quot;slides_per_view&quot;:&quot;1&quot;,&quot;slides_per_view_widescreen&quot;:&quot;1&quot;,&quot;slides_per_view_laptop&quot;:&quot;1&quot;,&quot;slides_per_view_tablet_extra&quot;:&quot;1&quot;,&quot;slides_per_view_tablet&quot;:&quot;1&quot;,&quot;slides_per_view_mobile_extra&quot;:&quot;1&quot;,&quot;skin&quot;:&quot;carousel&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;pagination&quot;:&quot;bullets&quot;,&quot;speed&quot;:500,&quot;autoplay&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;loop&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;space_between&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;space_between_widescreen&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;space_between_laptop&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;space_between_tablet_extra&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;space_between_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;space_between_mobile_extra&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;space_between_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]}}\" data-widget_type=\"media-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<link rel=\"stylesheet\" href=\"https:\/\/www.niederthalerhof.com\/wp-content\/plugins\/elementor-pro\/assets\/css\/widget-carousel.min.css?ver=1721981042\">\t\t<div class=\"elementor-swiper\">\n\t\t\t<div class=\"elementor-main-swiper swiper\">\n\t\t\t\t<div class=\"swiper-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"niederthalerhof-1\" style=\"background-image: url(&#039;https:\/\/www.niederthalerhof.com\/wp-content\/uploads\/2026\/09\/niederthalerhof-1-scaled.webp&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-18fa664e e-con-full e-flex e-con e-parent\" data-id=\"18fa664e\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-280e5db1 e-flex e-con-boxed e-con e-child\" data-id=\"280e5db1\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-35d26010 elementor-widget elementor-widget-heading\" data-id=\"35d26010\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.23.0 - 25-07-2024 *\/\n.elementor-heading-title{padding:0;margin:0;line-height:1}.elementor-widget-heading .elementor-heading-title[class*=elementor-size-]>a{color:inherit;font-size:inherit;line-height:inherit}.elementor-widget-heading .elementor-heading-title.elementor-size-small{font-size:15px}.elementor-widget-heading .elementor-heading-title.elementor-size-medium{font-size:19px}.elementor-widget-heading .elementor-heading-title.elementor-size-large{font-size:29px}.elementor-widget-heading .elementor-heading-title.elementor-size-xl{font-size:39px}.elementor-widget-heading .elementor-heading-title.elementor-size-xxl{font-size:59px}<\/style><h1 class=\"elementor-heading-title elementor-size-default\">Gustare senza glutine al Niederthalerhof<\/h1>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7fb8327c e-flex e-con-boxed e-con e-child\" data-id=\"7fb8327c\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-79afc365 elementor-widget elementor-widget-text-editor\" data-id=\"79afc365\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.23.0 - 25-07-2024 *\/\n.elementor-widget-text-editor.elementor-drop-cap-view-stacked .elementor-drop-cap{background-color:#69727d;color:#fff}.elementor-widget-text-editor.elementor-drop-cap-view-framed .elementor-drop-cap{color:#69727d;border:3px solid;background-color:transparent}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap{margin-top:8px}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap-letter{width:1em;height:1em}.elementor-widget-text-editor .elementor-drop-cap{float:left;text-align:center;line-height:1;font-size:50px}.elementor-widget-text-editor .elementor-drop-cap-letter{display:inline-block}<\/style>\t\t\t\t<p style=\"margin: 0cm;\"><span style=\"font-family: 'Segoe UI',sans-serif; color: #0d0d0d;\">Per i nostri ospiti affetti da celiachia abbiamo creato un\u2019offerta senza glutine pensata con cura, che unisce il piacere del buon cibo alla massima attenzione e sicurezza possibile.<\/span><\/p><p style=\"margin: 0cm;\"><span style=\"font-family: 'Segoe UI',sans-serif; color: #0d0d0d;\">L\u2019idea nasce dalla nostra esperienza familiare. Sappiamo quanto possa essere difficile mangiare senza glutine in modo sicuro e senza pensieri quando si \u00e8 in viaggio o in vacanza. Proprio per questo desideravamo creare un luogo in cui le persone affette da celiachia possano sentirsi completamente a proprio agio e in buone mani.<\/span><\/p><p style=\"margin: 0cm;\"><span style=\"font-family: 'Segoe UI',sans-serif; color: #0d0d0d;\">Oggi prepariamo personalmente il nostro pane senza glutine e realizziamo ogni giorno torte fresche, strudel di mele e altre specialit\u00e0 utilizzando ingredienti selezionati e lavorandoli con grande cura nella nostra cucina.<\/span><\/p><p style=\"margin: 0cm;\"><span style=\"font-family: 'Segoe UI',sans-serif; color: #0d0d0d;\">Anche nei nostri chalet desideriamo offrirvi la massima sicurezza possibile. Su richiesta mettiamo quindi a disposizione un<span class=\"apple-converted-space\">\u00a0<\/span><strong><span style=\"font-family: 'Segoe UI',sans-serif; font-weight: normal;\">kit cucina separato<\/span><\/strong><b>,<\/b> con utensili e accessori selezionati, affinch\u00e9 possiate preparare in autonomia i vostri piatti senza glutine in tutta tranquillit\u00e0.<\/span><\/p><p style=\"margin: 0cm;\"><span style=\"font-family: 'Segoe UI',sans-serif; color: #0d0d0d;\">Cos\u00ec potrete vivere la vostra vacanza al Niederthalerhof senza pensieri \u2013 dalla colazione fino alla tradizionale merenda altoatesina. Qualit\u00e0, sicurezza e autentico piacere sono per noi sempre al primo posto. Perch\u00e9, grazie alla nostra esperienza familiare, sappiamo quanto sia importante poter contare anche in vacanza su un\u2019alimentazione senza glutine sicura, accurata e affidabile.<\/span><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1178e2b1 e-con-full e-flex e-con e-parent\" data-id=\"1178e2b1\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1ad1b0d pfeillinksunten elementor-skin-carousel elementor-arrows-yes elementor-widget elementor-widget-media-carousel\" data-id=\"1ad1b0d\" data-element_type=\"widget\" data-settings=\"{&quot;slides_per_view&quot;:&quot;1&quot;,&quot;slides_per_view_widescreen&quot;:&quot;1&quot;,&quot;slides_per_view_laptop&quot;:&quot;1&quot;,&quot;slides_per_view_tablet_extra&quot;:&quot;1&quot;,&quot;slides_per_view_tablet&quot;:&quot;1&quot;,&quot;slides_per_view_mobile_extra&quot;:&quot;1&quot;,&quot;skin&quot;:&quot;carousel&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;show_arrows&quot;:&quot;yes&quot;,&quot;speed&quot;:500,&quot;autoplay&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;loop&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;space_between&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;space_between_widescreen&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;space_between_laptop&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;space_between_tablet_extra&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;space_between_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;space_between_mobile_extra&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;space_between_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]}}\" data-widget_type=\"media-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-swiper\">\n\t\t\t<div class=\"elementor-main-swiper swiper\">\n\t\t\t\t<div class=\"swiper-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/www.niederthalerhof.com\/wp-content\/uploads\/2026\/09\/niederthalerhof-2.webp\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"1ad1b0d\" data-elementor-lightbox-title=\"niederthalerhof-2\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mzg1MywidXJsIjoiaHR0cHM6XC9cL3d3dy5uaWVkZXJ0aGFsZXJob2YuY29tXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI2XC8wOVwvbmllZGVydGhhbGVyaG9mLTIud2VicCIsInNsaWRlc2hvdyI6IjFhZDFiMGQifQ%3D%3D\">\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"niederthalerhof-2\" style=\"background-image: url(&#039;https:\/\/www.niederthalerhof.com\/wp-content\/uploads\/2026\/09\/niederthalerhof-2.webp&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t<\/a>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Gustare senza glutine al Niederthalerhof Per i nostri ospiti affetti da celiachia abbiamo creato un\u2019offerta senza glutine pensata con cura, che unisce il piacere del buon cibo alla massima attenzione e sicurezza possibile. L\u2019idea nasce dalla nostra esperienza familiare. Sappiamo quanto possa essere difficile mangiare senza glutine in modo sicuro e senza pensieri quando si [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"class_list":["post-3858","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>senza glutine - niederthalerhof<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.niederthalerhof.com\/it\/glutenfrei\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"senza glutine - niederthalerhof\" \/>\n<meta property=\"og:description\" content=\"Gustare senza glutine al Niederthalerhof Per i nostri ospiti affetti da celiachia abbiamo creato un\u2019offerta senza glutine pensata con cura, che unisce il piacere del buon cibo alla massima attenzione e sicurezza possibile. L\u2019idea nasce dalla nostra esperienza familiare. Sappiamo quanto possa essere difficile mangiare senza glutine in modo sicuro e senza pensieri quando si [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.niederthalerhof.com\/it\/glutenfrei\/\" \/>\n<meta property=\"og:site_name\" content=\"niederthalerhof\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/niederthalerhof\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-09-01T13:39:01+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.niederthalerhof.com\/it\/glutenfrei\/\",\"url\":\"https:\/\/www.niederthalerhof.com\/it\/glutenfrei\/\",\"name\":\"senza glutine - niederthalerhof\",\"isPartOf\":{\"@id\":\"https:\/\/www.niederthalerhof.com\/it\/#website\"},\"datePublished\":\"2026-09-01T13:20:37+00:00\",\"dateModified\":\"2026-09-01T13:39:01+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.niederthalerhof.com\/it\/glutenfrei\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.niederthalerhof.com\/it\/glutenfrei\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.niederthalerhof.com\/it\/glutenfrei\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/www.niederthalerhof.com\/it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"senza glutine\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.niederthalerhof.com\/it\/#website\",\"url\":\"https:\/\/www.niederthalerhof.com\/it\/\",\"name\":\"niederthalerhof\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.niederthalerhof.com\/it\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.niederthalerhof.com\/it\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.niederthalerhof.com\/it\/#organization\",\"name\":\"niederthalerhof\",\"url\":\"https:\/\/www.niederthalerhof.com\/it\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.niederthalerhof.com\/it\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.niederthalerhof.com\/wp-content\/uploads\/2024\/05\/Gruppe-2461-2.svg\",\"contentUrl\":\"https:\/\/www.niederthalerhof.com\/wp-content\/uploads\/2024\/05\/Gruppe-2461-2.svg\",\"width\":345,\"height\":133,\"caption\":\"niederthalerhof\"},\"image\":{\"@id\":\"https:\/\/www.niederthalerhof.com\/it\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/niederthalerhof\/\",\"https:\/\/www.instagram.com\/niederthalerhof_chalets\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"senza glutine - niederthalerhof","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.niederthalerhof.com\/it\/glutenfrei\/","og_locale":"it_IT","og_type":"article","og_title":"senza glutine - niederthalerhof","og_description":"Gustare senza glutine al Niederthalerhof Per i nostri ospiti affetti da celiachia abbiamo creato un\u2019offerta senza glutine pensata con cura, che unisce il piacere del buon cibo alla massima attenzione e sicurezza possibile. L\u2019idea nasce dalla nostra esperienza familiare. Sappiamo quanto possa essere difficile mangiare senza glutine in modo sicuro e senza pensieri quando si [&hellip;]","og_url":"https:\/\/www.niederthalerhof.com\/it\/glutenfrei\/","og_site_name":"niederthalerhof","article_publisher":"https:\/\/www.facebook.com\/niederthalerhof\/","article_modified_time":"2026-09-01T13:39:01+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.niederthalerhof.com\/it\/glutenfrei\/","url":"https:\/\/www.niederthalerhof.com\/it\/glutenfrei\/","name":"senza glutine - niederthalerhof","isPartOf":{"@id":"https:\/\/www.niederthalerhof.com\/it\/#website"},"datePublished":"2026-09-01T13:20:37+00:00","dateModified":"2026-09-01T13:39:01+00:00","breadcrumb":{"@id":"https:\/\/www.niederthalerhof.com\/it\/glutenfrei\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.niederthalerhof.com\/it\/glutenfrei\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.niederthalerhof.com\/it\/glutenfrei\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.niederthalerhof.com\/it\/"},{"@type":"ListItem","position":2,"name":"senza glutine"}]},{"@type":"WebSite","@id":"https:\/\/www.niederthalerhof.com\/it\/#website","url":"https:\/\/www.niederthalerhof.com\/it\/","name":"niederthalerhof","description":"","publisher":{"@id":"https:\/\/www.niederthalerhof.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.niederthalerhof.com\/it\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.niederthalerhof.com\/it\/#organization","name":"niederthalerhof","url":"https:\/\/www.niederthalerhof.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.niederthalerhof.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.niederthalerhof.com\/wp-content\/uploads\/2024\/05\/Gruppe-2461-2.svg","contentUrl":"https:\/\/www.niederthalerhof.com\/wp-content\/uploads\/2024\/05\/Gruppe-2461-2.svg","width":345,"height":133,"caption":"niederthalerhof"},"image":{"@id":"https:\/\/www.niederthalerhof.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/niederthalerhof\/","https:\/\/www.instagram.com\/niederthalerhof_chalets\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.niederthalerhof.com\/it\/wp-json\/wp\/v2\/pages\/3858"}],"collection":[{"href":"https:\/\/www.niederthalerhof.com\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.niederthalerhof.com\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.niederthalerhof.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.niederthalerhof.com\/it\/wp-json\/wp\/v2\/comments?post=3858"}],"version-history":[{"count":4,"href":"https:\/\/www.niederthalerhof.com\/it\/wp-json\/wp\/v2\/pages\/3858\/revisions"}],"predecessor-version":[{"id":3866,"href":"https:\/\/www.niederthalerhof.com\/it\/wp-json\/wp\/v2\/pages\/3858\/revisions\/3866"}],"wp:attachment":[{"href":"https:\/\/www.niederthalerhof.com\/it\/wp-json\/wp\/v2\/media?parent=3858"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}